{"id":58797,"date":"2025-06-17T05:37:31","date_gmt":"2025-06-17T08:37:31","guid":{"rendered":"https:\/\/fmlatribu.com\/noticias\/?p=58797"},"modified":"2025-06-17T05:37:32","modified_gmt":"2025-06-17T08:37:32","slug":"despidos-en-jardines-maternales-comunitarios","status":"publish","type":"post","link":"https:\/\/fmlatribu.com\/noticias\/despidos-en-jardines-maternales-comunitarios\/","title":{"rendered":"Despidos en jardines maternales comunitarios"},"content":{"rendered":"\n<p>En la Ciudad de Buenos Aires hay siete establecimientos maternales p\u00fablicos conveniados, que son gestionados por organizaciones comunitarias y el Ministerio de Educaci\u00f3n de la Ciudad. Se ubican en zonas vulnerables de los barrios de Chacarita, el Bajo Flores, Barracas, en el barrio de los Piletones y en Villa Soldati y funcionan en el marco del \u00e1rea socioeducativa de la Direcci\u00f3n de Inclusi\u00f3n Educativa. <\/p>\n\n\n\n<p>Cada a\u00f1o las instituciones tienen que presentar los papeles del convenio, \u00ab<em>Nos cost\u00f3 un mont\u00f3n que nos den una cita para la firma del convenio, ya estamos a mitad de a\u00f1o a pesar de que presentamos todo en tiempo y forma<\/em>\u00ab, sostuvo <strong>Natalia<\/strong>, es <strong>referente <\/strong>del jard\u00edn <strong>Popular Comunitario Luces en el Bajo<\/strong>, que est\u00e1 en el Barrio de Bajo Flores, del movimiento Popular la Dignidad. Este a\u00f1o lo que sucedi\u00f3 cuando fueron a la firma del convenio \u00ab<em>y a pedir el alta de una de las compa\u00f1eras<\/em>\u00ab, nos indicaron que, \u00ab<em>no solamente no nos iban a dar el alta de nuestra compa\u00f1era, sino que a partir del 1 de julio nos iban a despedir a todas<\/em>, <em>porque consideraban que nuestros cargos estaban de m\u00e1s en los espacios y que con el plantel docente alcanzaba<\/em>\u00ab, relat\u00f3 <strong>Natalia<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/fmlatribu.com\/noticias\/wp-content\/uploads\/2025\/06\/nataliajardines1.mp3\"><\/audio><\/figure>\n\n\n\n<p>\u00ab<em>Se trata de un cargo que est\u00e1 reconocido por el ministerio desde 2013, que son fundamentales para el proyecto, para que puedan seguir funcionando. Lo que nos dicen es que tienen que reorganizar el Ministerio y que hay puestos que est\u00e1n de m\u00e1s<\/em>\u00ab, indic\u00f3 <strong>Natalia<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/fmlatribu.com\/noticias\/wp-content\/uploads\/2025\/06\/nataliajardines2.mp3\"><\/audio><\/figure>\n\n\n\n<p>\u00abA estos jardines asisten m\u00e1s de 100 ni\u00f1eces, que se estar\u00edan quedando sin jardines\u00bb, sostuvo <strong>Natalia<\/strong>. Se trata de ni\u00f1os y ni\u00f1as de entre 45 d\u00edas y 3 a\u00f1os de edad, si bien no es una instancia de educaci\u00f3n obligatoria, \u00ab<em>es importante poder acompa\u00f1ar los proyectos de las ni\u00f1eces<\/em>\u00ab, contin\u00fao <strong>Natalia<\/strong>. <\/p>\n\n\n\n<p>\u00ab<em>Queremos que se sepa que el Ministerio de Educaci\u00f3n bajo las falsas palabras de reorganizaci\u00f3n, lo que est\u00e1n haciendo es recortar y dejar a muchos trabajadores sin trabajo<\/em>\u00ab, finaliz\u00f3 <strong>Natalia<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Producci\u00f3n: Eso que falta<br>Foto: @lucesenelbajo<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Ciudad de Buenos Aires hay siete establecimientos maternales p\u00fablicos conveniados, que son gestionados por organizaciones comunitarias y el Ministerio de Educaci\u00f3n de la Ciudad. Se ubican en zonas vulnerables de los barrios de Chacarita, el Bajo Flores, Barracas, en el barrio de los Piletones y en Villa Soldati y funcionan en el marco [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":58800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[439,442],"tags":[1496,264,1495,1497,625],"class_list":["post-58797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-a-la-ciudad","category-trabajo","tag-bajo-flores","tag-ciudad-de-buenos-aires","tag-jardines-comunitarios","tag-ministerio-de-educacion-de-la-ciudad","tag-trabajo"],"_links":{"self":[{"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/posts\/58797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/comments?post=58797"}],"version-history":[{"count":2,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/posts\/58797\/revisions"}],"predecessor-version":[{"id":58802,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/posts\/58797\/revisions\/58802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/media\/58800"}],"wp:attachment":[{"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/media?parent=58797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/categories?post=58797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmlatribu.com\/noticias\/wp-json\/wp\/v2\/tags?post=58797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}